﻿{"id":390,"date":"2009-04-23T11:35:08","date_gmt":"2009-04-23T10:35:08","guid":{"rendered":"http:\/\/www.flapane.com\/blog\/?p=390"},"modified":"2016-08-17T18:00:58","modified_gmt":"2016-08-17T17:00:58","slug":"rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope","status":"publish","type":"post","link":"https:\/\/www.flapane.com\/blog\/2009\/04\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\/","title":{"rendered":"Rilasciata ufficialmente Ubuntu 9.04 Jaunty Jackalope"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone image\" src=\"https:\/\/ubuntunigeria.files.wordpress.com\/2007\/09\/masthead-cds.jpg\" alt=\"\" width=\"204\" height=\"95\" \/><\/p>\n<p style=\"text-align: justify;\">Sebbene preferisca le versioni LTS (Long term support) come la 8.04 nome in codice <em>Hardy<\/em>, non si pu\u00f2 non segnalare, con tanto di mirror italiano, il rilascio ufficiale, un paio di ore fa, della versione definitiva della nuova <strong>Jaunty Jackalope<\/strong> (o pi\u00f9 precisamente, i file .torrent sono stati aggiornati alle ore 9 italiane, ma le iso sono datate 20 aprile. Con ogni probabilit\u00e0 le iso saranno disponibili nella serata di oggi).<br \/>\nSecondo <a title=\"ubuntu jaunty boots in 15 seconds\" href=\"http:\/\/www.mattcutts.com\/blog\/ubuntu-904-boots-in-175-seconds\/\">MattCutts.com<\/a>, fra l&#8217;altro, ci sarebbe stato un grande boost nei tempi di caricamento (tutto da verificare con altre configurazioni hardware), addirittua 17 secondi con un Solid State Drive.<\/p>\n<p style=\"text-align: justify;\">Ricordiamo che per quanto riguarda la versione (K)Ubuntu, KDE3 (ahim\u00e8) \u00e8 stato abbandonato in favore del 4.<br \/>\nPer i nostalgici, bisogner\u00e0 aspettare che qualcuno si dedichi al progetto e compili kde3 per Jaunty, creando il proprio repository ppa.<\/p>\n<p style=\"text-align: justify;\">E&#8217;incluso il nuovo X.Org server 1.6\/GNOME 2.26;  Evolution 2.26.1 mailer.<br \/>\nDa menzionare \u00e8 l&#8217;inclusione del nuovo file system Ext4 e il kernel 2.26.8<\/p>\n<p style=\"text-align: justify;\">Per una lista pi\u00f9 dettagliata delle novit\u00e0, rimando al link ufficiale a <a title=\"ubuntu 9.04 official\" href=\"http:\/\/www.ubuntu.com\/getubuntu\/releasenotes\/904overview#New%20features%20since%20Ubuntu%208.10\">questo<\/a> indirizzo.<\/p>\n<p style=\"text-align: justify;\">Per avere una bella review con tanto di carrellata di screenshoot, consiglio <a title=\"ubuntu jaunty review\" href=\"https:\/\/web.archive.org\/web\/20121020101101\/http:\/\/www.tuxjournal.net\/screenshot-review-ubuntu-904\/\">questo<\/a> articolo di tuxjournal.<\/p>\n<p style=\"text-align: justify;\">Volete scaricare la nuovissima versione rilasciata sul mirror italiano?<br \/>\nRifornitevi pure sul mirror partenopeo del garr, a <a title=\"mirror garr na ubuntu jaunty\" href=\"http:\/\/na.mirror.garr.it\/mirrors\/ubuntu-releases\/\">questo<\/a> indirizzo, facendo attenzione che la data della iso da scaricare sia 23 Aprile e non 20, cosa che accadr\u00e0 nelle prossime ore, indi per cui state in campana \ud83d\ude42<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sebbene preferisca le versioni LTS (Long term support) come la 8.04 nome in codice Hardy, non si pu\u00f2 non segnalare, con tanto di mirror italiano, il rilascio ufficiale, un paio di ore fa, della versione definitiva della nuova Jaunty Jackalope (o pi\u00f9 precisamente, i file .torrent sono stati aggiornati alle ore 9 italiane, ma le iso sono datate 20 aprile. Con ogni probabilit\u00e0 le iso saranno disponibili nella serata di oggi).<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[112,300],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Sebbene preferisca le versioni LTS (Long term support) come la 8.04 nome in codice Hardy, non si pu\u00f2 non segnalare, con tanto di mirror italiano, il rilascio ufficiale, un paio di ore fa, della versione definitiva della nuova Jaunty Jackalope (o pi\u00f9 precisamente, i file .torrent sono stati aggiornati alle ore 9 italiane, ma le iso sono datate 20 aprile. Con ogni probabilit\u00e0 le iso saranno disponibili nella serata di oggi).\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"flapane\"\/>\n\t<meta name=\"keywords\" content=\"jaunty jackalope,ubuntu\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.flapane.com\/blog\/2009\/04\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/2009\\\/04\\\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\\\/#article\",\"name\":\"Rilasciata ufficialmente Ubuntu 9.04 Jaunty Jackalope | Flavio's blog\",\"headline\":\"Rilasciata ufficialmente Ubuntu 9.04 Jaunty Jackalope\",\"author\":{\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ubuntunigeria.files.wordpress.com\\\/2007\\\/09\\\/masthead-cds.jpg\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/2009\\\/04\\\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\\\/#articleImage\"},\"datePublished\":\"2009-04-23T11:35:08+02:00\",\"dateModified\":\"2016-08-17T18:00:58+02:00\",\"inLanguage\":\"it-IT\",\"commentCount\":7,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/2009\\\/04\\\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/2009\\\/04\\\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\\\/#webpage\"},\"articleSection\":\"Ubuntu, jaunty jackalope, Ubuntu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/2009\\\/04\\\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.flapane.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/category\\\/ubuntu\\\/#listItem\",\"name\":\"Ubuntu\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/category\\\/ubuntu\\\/#listItem\",\"position\":2,\"name\":\"Ubuntu\",\"item\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/category\\\/ubuntu\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/2009\\\/04\\\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\\\/#listItem\",\"name\":\"Rilasciata ufficialmente Ubuntu 9.04 Jaunty Jackalope\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/2009\\\/04\\\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\\\/#listItem\",\"position\":3,\"name\":\"Rilasciata ufficialmente Ubuntu 9.04 Jaunty Jackalope\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/category\\\/ubuntu\\\/#listItem\",\"name\":\"Ubuntu\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/#person\",\"name\":\"flapane\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/2009\\\/04\\\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e43beca0049bc27c912f758db3d8dcd?s=96&r=g\",\"width\":96,\"height\":96,\"caption\":\"flapane\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/author\\\/admin\\\/\",\"name\":\"flapane\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/2009\\\/04\\\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e43beca0049bc27c912f758db3d8dcd?s=96&r=g\",\"width\":96,\"height\":96,\"caption\":\"flapane\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/2009\\\/04\\\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\\\/#webpage\",\"url\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/2009\\\/04\\\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\\\/\",\"name\":\"Rilasciata ufficialmente Ubuntu 9.04 Jaunty Jackalope | Flavio's blog\",\"description\":\"Sebbene preferisca le versioni LTS (Long term support) come la 8.04 nome in codice Hardy, non si pu\\u00f2 non segnalare, con tanto di mirror italiano, il rilascio ufficiale, un paio di ore fa, della versione definitiva della nuova Jaunty Jackalope (o pi\\u00f9 precisamente, i file .torrent sono stati aggiornati alle ore 9 italiane, ma le iso sono datate 20 aprile. Con ogni probabilit\\u00e0 le iso saranno disponibili nella serata di oggi).\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/2009\\\/04\\\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2009-04-23T11:35:08+02:00\",\"dateModified\":\"2016-08-17T18:00:58+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/\",\"name\":\"Flavio's blog\",\"description\":\"Di tutto di pi\\u00f9, il blog del sito flapane.com\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Rilasciata ufficialmente Ubuntu 9.04 Jaunty Jackalope | Flavio's blog","description":"Sebbene preferisca le versioni LTS (Long term support) come la 8.04 nome in codice Hardy, non si pu\u00f2 non segnalare, con tanto di mirror italiano, il rilascio ufficiale, un paio di ore fa, della versione definitiva della nuova Jaunty Jackalope (o pi\u00f9 precisamente, i file .torrent sono stati aggiornati alle ore 9 italiane, ma le iso sono datate 20 aprile. Con ogni probabilit\u00e0 le iso saranno disponibili nella serata di oggi).","canonical_url":"https:\/\/www.flapane.com\/blog\/2009\/04\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"jaunty jackalope,ubuntu","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.flapane.com\/blog\/2009\/04\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\/#article","name":"Rilasciata ufficialmente Ubuntu 9.04 Jaunty Jackalope | Flavio's blog","headline":"Rilasciata ufficialmente Ubuntu 9.04 Jaunty Jackalope","author":{"@id":"https:\/\/www.flapane.com\/blog\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.flapane.com\/blog\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/ubuntunigeria.files.wordpress.com\/2007\/09\/masthead-cds.jpg","@id":"https:\/\/www.flapane.com\/blog\/2009\/04\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\/#articleImage"},"datePublished":"2009-04-23T11:35:08+02:00","dateModified":"2016-08-17T18:00:58+02:00","inLanguage":"it-IT","commentCount":7,"mainEntityOfPage":{"@id":"https:\/\/www.flapane.com\/blog\/2009\/04\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\/#webpage"},"isPartOf":{"@id":"https:\/\/www.flapane.com\/blog\/2009\/04\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\/#webpage"},"articleSection":"Ubuntu, jaunty jackalope, Ubuntu"},{"@type":"BreadcrumbList","@id":"https:\/\/www.flapane.com\/blog\/2009\/04\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.flapane.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.flapane.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.flapane.com\/blog\/category\/ubuntu\/#listItem","name":"Ubuntu"}},{"@type":"ListItem","@id":"https:\/\/www.flapane.com\/blog\/category\/ubuntu\/#listItem","position":2,"name":"Ubuntu","item":"https:\/\/www.flapane.com\/blog\/category\/ubuntu\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.flapane.com\/blog\/2009\/04\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\/#listItem","name":"Rilasciata ufficialmente Ubuntu 9.04 Jaunty Jackalope"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.flapane.com\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.flapane.com\/blog\/2009\/04\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\/#listItem","position":3,"name":"Rilasciata ufficialmente Ubuntu 9.04 Jaunty Jackalope","previousItem":{"@type":"ListItem","@id":"https:\/\/www.flapane.com\/blog\/category\/ubuntu\/#listItem","name":"Ubuntu"}}]},{"@type":"Person","@id":"https:\/\/www.flapane.com\/blog\/#person","name":"flapane","image":{"@type":"ImageObject","@id":"https:\/\/www.flapane.com\/blog\/2009\/04\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/6e43beca0049bc27c912f758db3d8dcd?s=96&r=g","width":96,"height":96,"caption":"flapane"}},{"@type":"Person","@id":"https:\/\/www.flapane.com\/blog\/author\/admin\/#author","url":"https:\/\/www.flapane.com\/blog\/author\/admin\/","name":"flapane","image":{"@type":"ImageObject","@id":"https:\/\/www.flapane.com\/blog\/2009\/04\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/6e43beca0049bc27c912f758db3d8dcd?s=96&r=g","width":96,"height":96,"caption":"flapane"}},{"@type":"WebPage","@id":"https:\/\/www.flapane.com\/blog\/2009\/04\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\/#webpage","url":"https:\/\/www.flapane.com\/blog\/2009\/04\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\/","name":"Rilasciata ufficialmente Ubuntu 9.04 Jaunty Jackalope | Flavio's blog","description":"Sebbene preferisca le versioni LTS (Long term support) come la 8.04 nome in codice Hardy, non si pu\u00f2 non segnalare, con tanto di mirror italiano, il rilascio ufficiale, un paio di ore fa, della versione definitiva della nuova Jaunty Jackalope (o pi\u00f9 precisamente, i file .torrent sono stati aggiornati alle ore 9 italiane, ma le iso sono datate 20 aprile. Con ogni probabilit\u00e0 le iso saranno disponibili nella serata di oggi).","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.flapane.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.flapane.com\/blog\/2009\/04\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\/#breadcrumblist"},"author":{"@id":"https:\/\/www.flapane.com\/blog\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.flapane.com\/blog\/author\/admin\/#author"},"datePublished":"2009-04-23T11:35:08+02:00","dateModified":"2016-08-17T18:00:58+02:00"},{"@type":"WebSite","@id":"https:\/\/www.flapane.com\/blog\/#website","url":"https:\/\/www.flapane.com\/blog\/","name":"Flavio's blog","description":"Di tutto di pi\u00f9, il blog del sito flapane.com","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.flapane.com\/blog\/#person"}}]}},"aioseo_meta_data":{"post_id":"390","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 07:14:05","updated":"2022-09-14 07:32:27","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.flapane.com\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.flapane.com\/blog\/category\/ubuntu\/\" title=\"Ubuntu\">Ubuntu<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRilasciata ufficialmente Ubuntu 9.04 Jaunty Jackalope\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.flapane.com\/blog"},{"label":"Ubuntu","link":"https:\/\/www.flapane.com\/blog\/category\/ubuntu\/"},{"label":"Rilasciata ufficialmente Ubuntu 9.04 Jaunty Jackalope","link":"https:\/\/www.flapane.com\/blog\/2009\/04\/rilasciata-ufficialmente-ubuntu-904-jaunty-jackalope\/"}],"_links":{"self":[{"href":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/posts\/390"}],"collection":[{"href":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/comments?post=390"}],"version-history":[{"count":0,"href":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/posts\/390\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/media?parent=390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/categories?post=390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/tags?post=390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}