﻿{"id":51,"count":2,"description":"","link":"https:\/\/www.flapane.com\/blog\/tag\/aquaterm\/","name":"aquaterm","slug":"aquaterm","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"noindex, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.flapane.com\/blog\/tag\/aquaterm\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/51\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.flapane.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/tag\\\/aquaterm\\\/#listItem\",\"name\":\"aquaterm\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/tag\\\/aquaterm\\\/#listItem\",\"position\":2,\"name\":\"aquaterm\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/51\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/51\\\/\",\"name\":\"aquaterm | Flavio's blog\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/51\\\/#breadcrumblist\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/#person\",\"name\":\"flapane\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/51\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e43beca0049bc27c912f758db3d8dcd?s=96&r=g\",\"width\":96,\"height\":96,\"caption\":\"flapane\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/\",\"name\":\"Flavio's blog\",\"description\":\"Di tutto di pi\\u00f9, il blog del sito flapane.com\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.flapane.com\\\/blog\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"aquaterm | Flavio's blog","description":"","canonical_url":"https:\/\/www.flapane.com\/blog\/tag\/aquaterm\/","robots":"noindex, max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/tags\/51\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.flapane.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.flapane.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.flapane.com\/blog\/tag\/aquaterm\/#listItem","name":"aquaterm"}},{"@type":"ListItem","@id":"https:\/\/www.flapane.com\/blog\/tag\/aquaterm\/#listItem","position":2,"name":"aquaterm","previousItem":{"@type":"ListItem","@id":"https:\/\/www.flapane.com\/blog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/tags\/51\/#collectionpage","url":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/tags\/51\/","name":"aquaterm | Flavio's blog","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.flapane.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/tags\/51\/#breadcrumblist"}},{"@type":"Person","@id":"https:\/\/www.flapane.com\/blog\/#person","name":"flapane","image":{"@type":"ImageObject","@id":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/tags\/51\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/6e43beca0049bc27c912f758db3d8dcd?s=96&r=g","width":96,"height":96,"caption":"flapane"}},{"@type":"WebSite","@id":"https:\/\/www.flapane.com\/blog\/#website","url":"https:\/\/www.flapane.com\/blog\/","name":"Flavio's blog","description":"Di tutto di pi\u00f9, il blog del sito flapane.com","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.flapane.com\/blog\/#person"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.flapane.com\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\taquaterm\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.flapane.com\/blog"},{"label":"aquaterm","link":"https:\/\/www.flapane.com\/blog\/tag\/aquaterm\/"}],"_links":{"self":[{"href":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/tags\/51"}],"collection":[{"href":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.flapane.com\/blog\/wp-json\/wp\/v2\/posts?tags=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}